{"id":2317,"date":"2018-02-08T10:48:31","date_gmt":"2018-02-08T10:48:31","guid":{"rendered":"https:\/\/2018.laspalmas.wordcamp.org\/?p=2317"},"modified":"2018-02-28T11:02:11","modified_gmt":"2018-02-28T11:02:11","slug":"fecha-limite-para-la-talla-de-las-camisetas","status":"publish","type":"post","link":"https:\/\/laspalmas.wordcamp.org\/2018\/fecha-limite-para-la-talla-de-las-camisetas\/","title":{"rendered":"Fecha l\u00edmite para la talla de las camisetas"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2186 size-medium aligncenter\" src=\"https:\/\/2018.laspalmas.wordcamp.org\/files\/2018\/02\/marca_gris-300x162.png\" alt=\"Marca de la WordCamp Gran Canaria en gris\" width=\"300\" height=\"162\" srcset=\"https:\/\/laspalmas.wordcamp.org\/2018\/files\/2018\/02\/marca_gris-300x162.png 300w, https:\/\/laspalmas.wordcamp.org\/2018\/files\/2018\/02\/marca_gris-768x414.png 768w, https:\/\/laspalmas.wordcamp.org\/2018\/files\/2018\/02\/marca_gris-1024x553.png 1024w, https:\/\/laspalmas.wordcamp.org\/2018\/files\/2018\/02\/marca_gris-500x270.png 500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p style=\"text-align: left\"><strong>Hola WordPresser@s!<\/strong><\/p>\n<p style=\"text-align: left\">Para los que a\u00fan no lo sab\u00e9is, cuando compras la entrada de la #WCGranCanaria, puedes elegir la talla de tu camiseta. \u00a1Ah! \u00bfQue no sab\u00edas que regalamos una camiseta con cada entrada? pues ya lo sabes.<\/p>\n<p style=\"text-align: left\"><strong>El lunes 12 de febrero por la ma\u00f1ana a las 10:00<\/strong> ser\u00e1 el momento en el que hagamos el pedido de camisetas, por lo que os recomendamos que compr\u00e9is vuestras entradas antes de esa fecha para poder asegurar que tendr\u00e9is la talla correcta en vuestra bolsa de bienvenida.<\/p>\n<p style=\"text-align: left\">\u00a1No esper\u00e9is m\u00e1s!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hola WordPresser@s! Para los que a\u00fan no lo sab\u00e9is, cuando compras la entrada de la #WCGranCanaria, puedes elegir la talla de tu camiseta. \u00a1Ah! \u00bfQue no sab\u00edas que regalamos una camiseta con cada entrada? pues ya lo sabes. El lunes 12 de febrero por la ma\u00f1ana a las 10:00 ser\u00e1 el momento en el que &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/laspalmas.wordcamp.org\/2018\/fecha-limite-para-la-talla-de-las-camisetas\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abFecha l\u00edmite para la talla de las camisetas\u00bb<\/span><\/a><\/p>\n","protected":false},"author":15008105,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[106],"tags":[],"class_list":["post-2317","post","type-post","status-publish","format-standard","hentry","category-general"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheMP8-Bn","jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/laspalmas.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts\/2317","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laspalmas.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laspalmas.wordcamp.org\/2018\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laspalmas.wordcamp.org\/2018\/wp-json\/wp\/v2\/users\/15008105"}],"replies":[{"embeddable":true,"href":"https:\/\/laspalmas.wordcamp.org\/2018\/wp-json\/wp\/v2\/comments?post=2317"}],"version-history":[{"count":7,"href":"https:\/\/laspalmas.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts\/2317\/revisions"}],"predecessor-version":[{"id":2958,"href":"https:\/\/laspalmas.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts\/2317\/revisions\/2958"}],"wp:attachment":[{"href":"https:\/\/laspalmas.wordcamp.org\/2018\/wp-json\/wp\/v2\/media?parent=2317"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laspalmas.wordcamp.org\/2018\/wp-json\/wp\/v2\/categories?post=2317"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laspalmas.wordcamp.org\/2018\/wp-json\/wp\/v2\/tags?post=2317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}