{"id":2345,"date":"2018-02-08T16:27:05","date_gmt":"2018-02-08T16:27:05","guid":{"rendered":"https:\/\/2018.laspalmas.wordcamp.org\/?p=2345"},"modified":"2018-02-28T11:01:25","modified_gmt":"2018-02-28T11:01:25","slug":"conoce-a-nuestro-ponente-juanjo-mestre","status":"publish","type":"post","link":"https:\/\/laspalmas.wordcamp.org\/2018\/conoce-a-nuestro-ponente-juanjo-mestre\/","title":{"rendered":"Conoce a nuestro ponente: Juanjo Mestre"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-2346 alignleft\" src=\"https:\/\/2018.laspalmas.wordcamp.org\/files\/2018\/02\/JuanjoMestre_FB-300x300.png\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/laspalmas.wordcamp.org\/2018\/files\/2018\/02\/JuanjoMestre_FB-300x300.png 300w, https:\/\/laspalmas.wordcamp.org\/2018\/files\/2018\/02\/JuanjoMestre_FB-150x150.png 150w, https:\/\/laspalmas.wordcamp.org\/2018\/files\/2018\/02\/JuanjoMestre_FB-768x768.png 768w, https:\/\/laspalmas.wordcamp.org\/2018\/files\/2018\/02\/JuanjoMestre_FB-100x100.png 100w, https:\/\/laspalmas.wordcamp.org\/2018\/files\/2018\/02\/JuanjoMestre_FB.png 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p style=\"text-align: left\"><strong>\u00bfQui\u00e9n es Juanjo?<\/strong><\/p>\n<p style=\"text-align: left\">Juanjo Mestre es Supervisor Creativo y UX Specialist en FLUOR Lifestyle. Adem\u00e1s, es fundador de la Asociaci\u00f3n de la Publicidad y ha sido premiado en el Festival Internacional DokFestivalen de narrativa audiovisual, as\u00ed como en festivales publicitarios de la talla de El Sol o Agripina.<\/p>\n<p style=\"text-align: left\">Por otro lado, ha sido ponente en las IV Jornadas Maestros de la Comunicaci\u00f3n y los Medios, moderador de las I Jornadas J\u00f3venes Publicitarios, adem\u00e1s de impartir conferencias en lugares como la Universidad Complutense de Madrid o ICADE. Juanjo es, adem\u00e1s, profesor de conceptualizaci\u00f3n creativa en el Postgrado en Branded Content y Transmedia Storytelling de Inesdi.<\/p>\n<p style=\"text-align: left\">Orientado a la Resoluci\u00f3n Creativa de Problemas (Creative Problem Solving) y la Creatividad Centrada en el Usuario, a lo largo de su carrera ha trabajado para marcas como ING, NBC Universal, Control Feel, Movistar+, Calle 13, Pescanova, o Syfy.<\/p>\n<p style=\"text-align: left\"><strong>\u00bfDe qu\u00e9 nos va a hablar Juanjo?<\/strong><\/p>\n<p style=\"text-align: left\"><!--td {border: 1px solid #ccc;}br {mso-data-placement:same-cell;}-->Cuando todo podemos producir contenidos, \u00bfc\u00f3mo hacemos que estos sean relevantes para nuestro p\u00fablico? T\u00fa eres una marca y tu sitio web el canal para llegar a tu audiencia, \u00bfpor qu\u00e9 un usuario preferir\u00eda visitar tu blog en lugar de ver una serie?<\/p>\n<p style=\"text-align: left\">En esta ponencia nos adentraremos en cuestiones como: \u00bfqui\u00e9n es mi p\u00fablico y c\u00f3mo es? \u00bfcu\u00e1l es mi posicionamiento? \u00bfc\u00f3mo podemos estudiar a nuestros usuarios para producir contenido que quieran compartir? \u00bfqu\u00e9 aporta mi contenido digital en un mundo hipersaturado? \u00bfcu\u00e1l es la misi\u00f3n del contenido que voy a producir? \u00bfc\u00f3mo pensar y decidir mi pr\u00f3xima publicaci\u00f3n?<\/p>\n<p style=\"text-align: left\">Bueno, con este curr\u00edculum y este contenido, \u00a1no nos lo podemos perder!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfQui\u00e9n es Juanjo? Juanjo Mestre es Supervisor Creativo y UX Specialist en FLUOR Lifestyle. Adem\u00e1s, es fundador de la Asociaci\u00f3n de la Publicidad y ha sido premiado en el Festival Internacional DokFestivalen de narrativa audiovisual, as\u00ed como en festivales publicitarios de la talla de El Sol o Agripina. Por otro lado, ha sido ponente en &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/laspalmas.wordcamp.org\/2018\/conoce-a-nuestro-ponente-juanjo-mestre\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abConoce a nuestro ponente: Juanjo Mestre\u00bb<\/span><\/a><\/p>\n","protected":false},"author":15008105,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10633],"tags":[],"class_list":["post-2345","post","type-post","status-publish","format-standard","hentry","category-ponentes"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheMP8-BP","jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/laspalmas.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts\/2345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laspalmas.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laspalmas.wordcamp.org\/2018\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laspalmas.wordcamp.org\/2018\/wp-json\/wp\/v2\/users\/15008105"}],"replies":[{"embeddable":true,"href":"https:\/\/laspalmas.wordcamp.org\/2018\/wp-json\/wp\/v2\/comments?post=2345"}],"version-history":[{"count":5,"href":"https:\/\/laspalmas.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts\/2345\/revisions"}],"predecessor-version":[{"id":2955,"href":"https:\/\/laspalmas.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts\/2345\/revisions\/2955"}],"wp:attachment":[{"href":"https:\/\/laspalmas.wordcamp.org\/2018\/wp-json\/wp\/v2\/media?parent=2345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laspalmas.wordcamp.org\/2018\/wp-json\/wp\/v2\/categories?post=2345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laspalmas.wordcamp.org\/2018\/wp-json\/wp\/v2\/tags?post=2345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}