{"id":2384,"date":"2018-02-09T11:45:52","date_gmt":"2018-02-09T11:45:52","guid":{"rendered":"https:\/\/2018.laspalmas.wordcamp.org\/?p=2384"},"modified":"2018-02-28T10:57:26","modified_gmt":"2018-02-28T10:57:26","slug":"conoce-a-nuestro-ponente-luis-montoya","status":"publish","type":"post","link":"https:\/\/laspalmas.wordcamp.org\/2018\/conoce-a-nuestro-ponente-luis-montoya\/","title":{"rendered":"Conoce a nuestro ponente: Luis Montoya"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-2385 alignleft\" src=\"https:\/\/2018.laspalmas.wordcamp.org\/files\/2018\/02\/LuisMontoya_FB-300x300.png\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/laspalmas.wordcamp.org\/2018\/files\/2018\/02\/LuisMontoya_FB-300x300.png 300w, https:\/\/laspalmas.wordcamp.org\/2018\/files\/2018\/02\/LuisMontoya_FB-150x150.png 150w, https:\/\/laspalmas.wordcamp.org\/2018\/files\/2018\/02\/LuisMontoya_FB-768x768.png 768w, https:\/\/laspalmas.wordcamp.org\/2018\/files\/2018\/02\/LuisMontoya_FB-100x100.png 100w, https:\/\/laspalmas.wordcamp.org\/2018\/files\/2018\/02\/LuisMontoya_FB.png 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p style=\"text-align: left\"><strong>\u00bfQui\u00e9n es Luis?<\/strong><\/p>\n<p style=\"text-align: left\">Luis es un amante de la inform\u00e1tica. Descubr\u00ed WordPress y me enamor\u00e9. Adoro hacer fotos. Me gusta mucho crear contenidos. Ahora mismo creo contenido para 5 blogs distintos de diferentes tem\u00e1ticas, desde WordPress hasta comida. Me muevo muy bien por las redes sociales. Estoy encantado con la Comunidad de WordPress por eso intento compartir lo que he aprendido durante todos estos a\u00f1os. Creador de contenido, creativo y como dicen por aqu\u00ed culo inquieto. Aparte de todo eso soy un amante del caf\u00e9. Si me ves an\u00edmate a hablar conmigo.<\/p>\n<p style=\"text-align: left\"><strong>\u00bfDe qu\u00e9 nos va a hablar Luis?<\/strong><\/p>\n<p style=\"text-align: left\">Nos dice: explicar\u00e9 diversas t\u00e9cnicas para atraer tr\u00e1fico a nuestro blog\/tienda\/pagina web. Usando las Redes Sociales, el email marketing y otra serie de t\u00e9cnicas para atraer tr\u00e1fico a nuestra web. Y luego ya dentro de la web intentar que se subscriban a nuestra newsletter o que compren algo en nuestra tienda online. Son t\u00e9cnica m\u00e1s que probados y que utilizan los grandes.<\/p>\n<p style=\"text-align: left\">Ya sabes qu\u00e9 charla tienes que ver para aumentar el tr\u00e1fico de tu web. \u00a1No te la pierdas!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfQui\u00e9n es Luis? Luis es un amante de la inform\u00e1tica. Descubr\u00ed WordPress y me enamor\u00e9. Adoro hacer fotos. Me gusta mucho crear contenidos. Ahora mismo creo contenido para 5 blogs distintos de diferentes tem\u00e1ticas, desde WordPress hasta comida. Me muevo muy bien por las redes sociales. Estoy encantado con la Comunidad de WordPress por eso &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/laspalmas.wordcamp.org\/2018\/conoce-a-nuestro-ponente-luis-montoya\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abConoce a nuestro ponente: Luis Montoya\u00bb<\/span><\/a><\/p>\n","protected":false},"author":15008105,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10633],"tags":[],"class_list":["post-2384","post","type-post","status-publish","format-standard","hentry","category-ponentes"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheMP8-Cs","jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/laspalmas.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts\/2384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laspalmas.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laspalmas.wordcamp.org\/2018\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laspalmas.wordcamp.org\/2018\/wp-json\/wp\/v2\/users\/15008105"}],"replies":[{"embeddable":true,"href":"https:\/\/laspalmas.wordcamp.org\/2018\/wp-json\/wp\/v2\/comments?post=2384"}],"version-history":[{"count":3,"href":"https:\/\/laspalmas.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts\/2384\/revisions"}],"predecessor-version":[{"id":2951,"href":"https:\/\/laspalmas.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts\/2384\/revisions\/2951"}],"wp:attachment":[{"href":"https:\/\/laspalmas.wordcamp.org\/2018\/wp-json\/wp\/v2\/media?parent=2384"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laspalmas.wordcamp.org\/2018\/wp-json\/wp\/v2\/categories?post=2384"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laspalmas.wordcamp.org\/2018\/wp-json\/wp\/v2\/tags?post=2384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}