{"id":2883,"date":"2018-02-23T06:05:21","date_gmt":"2018-02-23T06:05:21","guid":{"rendered":"https:\/\/2018.laspalmas.wordcamp.org\/?p=2883"},"modified":"2018-02-28T09:46:45","modified_gmt":"2018-02-28T09:46:45","slug":"conoce-a-nuestro-ponente-vineet-talwar","status":"publish","type":"post","link":"https:\/\/laspalmas.wordcamp.org\/2018\/conoce-a-nuestro-ponente-vineet-talwar\/","title":{"rendered":"Conoce a nuestro ponente Vineet Talwar"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-2884 alignleft\" src=\"https:\/\/2018.laspalmas.wordcamp.org\/files\/2018\/02\/VineetTalwar_FB-300x300.png\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/laspalmas.wordcamp.org\/2018\/files\/2018\/02\/VineetTalwar_FB-300x300.png 300w, https:\/\/laspalmas.wordcamp.org\/2018\/files\/2018\/02\/VineetTalwar_FB-150x150.png 150w, https:\/\/laspalmas.wordcamp.org\/2018\/files\/2018\/02\/VineetTalwar_FB-768x768.png 768w, https:\/\/laspalmas.wordcamp.org\/2018\/files\/2018\/02\/VineetTalwar_FB-100x100.png 100w, https:\/\/laspalmas.wordcamp.org\/2018\/files\/2018\/02\/VineetTalwar_FB.png 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p style=\"text-align: left\"><strong>\u00bfQui\u00e9n es Vineet?<\/strong><\/p>\n<p style=\"text-align: left\">Vineet descubri\u00f3 su amor por WordPress gracias a un amigo. Comenz\u00f3 a desarrollar numerosos sitios web e ir aprendiendo cada d\u00eda m\u00e1s sobre WordPress. Est\u00e1 relacionado con WordPress desde 2012. Co-fund\u00f3 su primera compa\u00f1\u00eda a la edad de 20 a\u00f1os. Vineet es cofundador y l\u00edder t\u00e9cnico de FireMud FM, la estaci\u00f3n de radio online basada puramente en WordPress e Indicium Crest &#8211; Una agencia de desarrollo web remota que, c\u00f3mo no, se centr\u00f3 en WordPress. Gestiona ambas compa\u00f1\u00edas en el frente t\u00e9cnico, su amor por WordPress simplemente sigue creciendo. Ha trabajado en m\u00e1s de 50 proyectos de forma remota administr\u00e1ndolas y desarroll\u00e1ndolas. Tambi\u00e9n ha sido asociado en varias empresas consultoras y gui\u00e1ndolas con recursos t\u00e9cnicos, actualmente reside en Frankfurt, Alemania.\u00a0Adem\u00e1s de desarrollar sitios web, es un fot\u00f3grafo aficionado.<\/p>\n<p style=\"text-align: left\"><strong>\u00bfDe qu\u00e9 nos va a hablar Vineet?<\/strong><\/p>\n<p style=\"text-align: left\">Las agencias de todo el mundo trabajan de forma correcta en el desarrollo de sitios web WordPress.\u00a0La forma m\u00e1s com\u00fan de hacerlo es crear m\u00faltiples instalaciones por separado. Pero, \u00bfy si hay una manera m\u00e1s simple?. En esta charla hablemos de la red de instalaciones de WordPress llamada WordPress Multisite. La charla tratar\u00e1 sobre c\u00f3mo mantener eficazmente entornos de Staging en Multisite y migrarlos sin incidencias al servidor de producci\u00f3n.<\/p>\n<p style=\"text-align: left\">Adem\u00e1s, Vineet hablar\u00e1 sobre qu\u00e9 se debe considerar para mantener una instalaci\u00f3n de red que ejecute cientos de sitios de m\u00faltiples sitios y escalarlos de manera efectiva; as\u00ed como qu\u00e9 herramientas y complementos est\u00e1n disponibles para facilitar el flujo de trabajo. Finalmente, y como a\u00f1adido, ir\u00e1 m\u00e1s lejos y tocar\u00e1 el tema sobre la red de redes y c\u00f3mo configurar una red de redes manteni\u00e9ndola de manera efectiva.<\/p>\n<p style=\"text-align: left\">Con todo, la idea detr\u00e1s de la charla es educar sobre el mantenimiento efectivo de una red y red de redes en WordPress.<\/p>\n<p style=\"text-align: left\">Anota esta charla en tu lista de deseos para esta WordCamp Gran Canaria, \u00a1all\u00ed nos vemos!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfQui\u00e9n es Vineet? Vineet descubri\u00f3 su amor por WordPress gracias a un amigo. Comenz\u00f3 a desarrollar numerosos sitios web e ir aprendiendo cada d\u00eda m\u00e1s sobre WordPress. Est\u00e1 relacionado con WordPress desde 2012. Co-fund\u00f3 su primera compa\u00f1\u00eda a la edad de 20 a\u00f1os. Vineet es cofundador y l\u00edder t\u00e9cnico de FireMud FM, la estaci\u00f3n de &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/laspalmas.wordcamp.org\/2018\/conoce-a-nuestro-ponente-vineet-talwar\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abConoce a nuestro ponente Vineet Talwar\u00bb<\/span><\/a><\/p>\n","protected":false},"author":15008105,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10633],"tags":[],"class_list":["post-2883","post","type-post","status-publish","format-standard","hentry","category-ponentes"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheMP8-Kv","jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/laspalmas.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts\/2883","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laspalmas.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laspalmas.wordcamp.org\/2018\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laspalmas.wordcamp.org\/2018\/wp-json\/wp\/v2\/users\/15008105"}],"replies":[{"embeddable":true,"href":"https:\/\/laspalmas.wordcamp.org\/2018\/wp-json\/wp\/v2\/comments?post=2883"}],"version-history":[{"count":4,"href":"https:\/\/laspalmas.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts\/2883\/revisions"}],"predecessor-version":[{"id":2912,"href":"https:\/\/laspalmas.wordcamp.org\/2018\/wp-json\/wp\/v2\/posts\/2883\/revisions\/2912"}],"wp:attachment":[{"href":"https:\/\/laspalmas.wordcamp.org\/2018\/wp-json\/wp\/v2\/media?parent=2883"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laspalmas.wordcamp.org\/2018\/wp-json\/wp\/v2\/categories?post=2883"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laspalmas.wordcamp.org\/2018\/wp-json\/wp\/v2\/tags?post=2883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}